{"id":218,"count":1,"description":"","link":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/","name":"entrepreneurship","slug":"entrepreneurship","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des entrepreneurship - ROGEAP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des entrepreneurship - ROGEAP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/\" \/>\n<meta property=\"og:site_name\" content=\"ROGEAP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ERogeap\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/tag\\\/entrepreneurship\\\/\",\"url\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/tag\\\/entrepreneurship\\\/\",\"name\":\"Archives des entrepreneurship - ROGEAP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/tag\\\/entrepreneurship\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/tag\\\/entrepreneurship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"entrepreneurship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/\",\"name\":\"ROGEAP\",\"description\":\"Projet R\u00e9gional d\u2019Acc\u00e8s \u00e0 l\u2019Electricit\u00e9 Hors R\u00e9seau\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#organization\",\"name\":\"Projet d\u2019acc\u00e8s \u00e0 l\u2019\u00e9lectricit\u00e9 hors r\u00e9seau\",\"url\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecowas.rogeap.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2.png\",\"contentUrl\":\"https:\\\/\\\/ecowas.rogeap.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2.png\",\"width\":1359,\"height\":743,\"caption\":\"Projet d\u2019acc\u00e8s \u00e0 l\u2019\u00e9lectricit\u00e9 hors r\u00e9seau\"},\"image\":{\"@id\":\"https:\\\/\\\/ecowas.rogeap.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EcowasRogeap\",\"https:\\\/\\\/x.com\\\/ERogeap\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecowas-rogeap-regional-off-grid-electricity-access-project\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des entrepreneurship - ROGEAP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/","og_locale":"en_US","og_type":"article","og_title":"Archives des entrepreneurship - ROGEAP","og_url":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/","og_site_name":"ROGEAP","twitter_card":"summary_large_image","twitter_site":"@ERogeap","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/","url":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/","name":"Archives des entrepreneurship - ROGEAP","isPartOf":{"@id":"https:\/\/ecowas.rogeap.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ecowas.rogeap.org\/en\/tag\/entrepreneurship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ecowas.rogeap.org\/en\/accueil\/"},{"@type":"ListItem","position":2,"name":"entrepreneurship"}]},{"@type":"WebSite","@id":"https:\/\/ecowas.rogeap.org\/en\/#website","url":"https:\/\/ecowas.rogeap.org\/en\/","name":"ROGEAP","description":"Projet R\u00e9gional d\u2019Acc\u00e8s \u00e0 l\u2019Electricit\u00e9 Hors R\u00e9seau","publisher":{"@id":"https:\/\/ecowas.rogeap.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecowas.rogeap.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecowas.rogeap.org\/en\/#organization","name":"Projet d\u2019acc\u00e8s \u00e0 l\u2019\u00e9lectricit\u00e9 hors r\u00e9seau","url":"https:\/\/ecowas.rogeap.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecowas.rogeap.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ecowas.rogeap.org\/wp-content\/uploads\/2023\/08\/2.png","contentUrl":"https:\/\/ecowas.rogeap.org\/wp-content\/uploads\/2023\/08\/2.png","width":1359,"height":743,"caption":"Projet d\u2019acc\u00e8s \u00e0 l\u2019\u00e9lectricit\u00e9 hors r\u00e9seau"},"image":{"@id":"https:\/\/ecowas.rogeap.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EcowasRogeap","https:\/\/x.com\/ERogeap","https:\/\/www.linkedin.com\/company\/ecowas-rogeap-regional-off-grid-electricity-access-project"]}]}},"_links":{"self":[{"href":"https:\/\/ecowas.rogeap.org\/en\/wp-json\/wp\/v2\/tags\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecowas.rogeap.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ecowas.rogeap.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ecowas.rogeap.org\/en\/wp-json\/wp\/v2\/posts?tags=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}